{"id":3958,"date":"2024-10-04T14:37:46","date_gmt":"2024-10-04T12:37:46","guid":{"rendered":"https:\/\/apiaforautism.org\/politique-de-confidentialite\/"},"modified":"2024-10-30T10:36:43","modified_gmt":"2024-10-30T09:36:43","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<div id=\"field_powc5dc0e0f128d4019\" class=\"container-fluid px-0 flexible_section block_columns\">\n <div id=\"field_powc5dc0e0f128d4019_inner\" class=\"container flexible_section_inner\">\n\n   <div class=\"row flexible_section_content\">\n\n   <div class=\"col-sm-12 colonne colonne1\">\n    <div class=\"colonne_inner  text-left\">\n<h1>Pol\u00edtica de privacidad<\/h1>\n    <\/div>\n   <\/div>\n  <\/div>\n\n <\/div>\n<\/div>\n\n\n<div id=\"field_pow32bbd51e262a44dc\" class=\"container-fluid px-0 flexible_section block_rgpd\">\n <div id=\"field_pow32bbd51e262a44dc_inner\" class=\"container flexible_section_inner\">\n\n  <div class=\"row flexible_section_content\">\n\n   <div class=\"col-md-12 col-lg colonne\">\n<h2>1. Objet<\/h2>\n<p>Lors de l&#8217;utilisation des sites accessibles aux adresses <a href=\"https:\/\/apiaforautism.org\/\" target=\"_blank\" rel=\"noopener\">apiaforautism.org<\/a> (le(s) &laquo; Site(s) &raquo;), Groupe SOS Transition \u00c9cologique et Territoires dont les coordonn\u00e9es sont d\u00e9taill\u00e9es \u00e0 l&#8217;Article 2 ci-dessous est amen\u00e9e \u00e0 collecter des donn\u00e9es personnelles des Utilisateurs (les &laquo; Donn\u00e9es Personnelles &raquo;).<\/p>\n<p>La pr\u00e9sente charte de protection des donn\u00e9es personnelles (ci-apr\u00e8s la &laquo; Charte &raquo;) a pour objet d&#8217;informer les Utilisateurs de l&#8217;utilisation faite par Groupe SOS Transition \u00c9cologique et Territoires des Donn\u00e9es Personnelles. Cette utilisation est faite dans le respect de la Loi n\u00b0 78-17 du 6 janvier 1978 relative \u00e0 l&rsquo;informatique, aux fichiers et aux libert\u00e9s, modifi\u00e9e par la Loi n\u00b02004-801 du 6 ao\u00fbt 2004 et par la loi n\u00b0 2018-493 du 20 juin 2018 (la &laquo; Loi Informatique et Libert\u00e9s &raquo;) et, de la Directive du 12 juillet 2002 modifi\u00e9e par la Directive 2009\/136\/CE (la &laquo; Directive ePrivacy &raquo;) et, du R\u00e8glement (UE) 20<\/p>\n<h2>2. D\u00e9finitions<\/h2>\n<p>Les termes &laquo; donn\u00e9es \u00e0 caract\u00e8re personnel &raquo; (&laquo; Donn\u00e9es Personnelles &raquo;), &laquo; Traiter\/Traitement &raquo;, &laquo; Responsable du Traitement &raquo;, &laquo; Sous-Traitant &raquo;, &laquo; Destinataire(s) &raquo;, &laquo; Consentement &raquo;, ont la m\u00eame signification que celle \u00e9nonc\u00e9e \u00e0 l&#8217;Article 4 du RGPD.<\/p>\n<p>&laquo; Utilisateur(s) &raquo; d\u00e9signe toute personne physique acc\u00e9dant au(x) Site(s) et Services sans avoir cr\u00e9\u00e9 de Compte Membre, et n&#8217;utilisant que certaines fonctionnalit\u00e9s du\/des Site(s) ou Services de Groupe SOS Transition \u00c9cologique et Territoires ;<\/p>\n<p>&laquo; Tiers &raquo; d\u00e9signe toute personne physique ou morale tiers \u00e0 Groupe SOS Transition \u00c9cologique et Territoires \u00e0 un Utilisateur ;<\/p>\n<p>&laquo; Services &raquo; d\u00e9signent tout ou partie des services propos\u00e9s par Groupe SOS Transition \u00c9cologique et Territoires sur son site ;<\/p>\n<p>&laquo; Site(s) &raquo; d\u00e9signe le(s) site(s) internet \u00e9dit\u00e9(s) les Services disponibles aux adresses <a href=\"https:\/\/apiaforautism.org\/\" target=\"_blank\" rel=\"noopener\">apiaforautism.org<\/a> ou tout autre site en rapport avec les Services.<\/p>\n<h2>3. Finalit\u00e9s et responsable de traitement des donn\u00e9es personnelles<\/h2>\n<p>Nous attachons la plus grande importance au respect de votre vie priv\u00e9e et \u00e0 la protection de vos Donn\u00e9es Personnelles. C&#8217;est pourquoi le Groupe SOS Transition \u00c9cologique et Territoires traite vos Donn\u00e9es Personnelles, dans le respect de la R\u00e9glementation Applicable, \u00e0 des fins :<\/p>\n<ul>\n<li>de prise de contact avec les Utilisateurs et de gestion de la relation avec les Utilisateurs ;<\/li>\n<li>d&#8217;informer les Utilisateurs et les   des actualit\u00e9s \u00e9v\u00e8nements, et autres activit\u00e9s du Groupe SOS Transition \u00c9cologique et Territoires ;<\/li>\n<li>d&#8217;offrir des Services en relation avec les activit\u00e9s du Groupe SOS Transition \u00c9cologique et Territoires;<\/li>\n<li>de consulter et conserver les informations relatives \u00e0 la navigation sur les Sites susceptibles d&#8217;\u00eatre enregistr\u00e9es dans des fichiers &laquo; cookies &raquo; (d\u00e9finis \u00e0 l&#8217;Article 9 ci-dessous).<\/li>\n<\/ul>\n<p>Pour ces finalit\u00e9s uniquement, le Responsable de Traitement des Donn\u00e9es Personnelles est Groupe SOS Transition \u00c9cologique et Territoires 102c rue Amelot 75011 Paris, dont les coordonn\u00e9es de contact se trouvent \u00e0 l&#8217;Article 10 ci-dessous.<\/p>\n<h2>4. Quelles sont les donn\u00e9es personnelles collect\u00e9es, pour quelles finalit\u00e9s ?<\/h2>\n<p>Lors de la collecte des Donn\u00e9es Personnelles, l&#8217;Utilisateur sera inform\u00e9 si certaines Donn\u00e9es Personnelles doivent \u00eatre obligatoirement renseign\u00e9es ou si elles sont facultatives. A d\u00e9faut de renseignement des Donn\u00e9es Personnelles qui doivent \u00eatre obligatoirement collect\u00e9es, l&#8217;acc\u00e8s \u00e0 certaines fonctionnalit\u00e9s des Services sera impossible. Le Groupe SOS Transition \u00c9cologique et Territoires pourra \u00eatre amen\u00e9e \u00e0 collecter les cat\u00e9gories de Donn\u00e9es Personnelles suivantes:<\/p>\n<p><\/p>\n<p><strong>4.1 Concernant les Utilisateurs<\/strong><\/p>\n<ul>\n<li>Les nom, pr\u00e9nom et adresse de courrier \u00e9lectronique en vue de recevoir la newsletter de Groupe SOS Transition \u00c9cologique et Territoires. La d\u00e9claration de Consentement passe par la transmission volontaire de ces informations de l&#8217;Utilisateur dans chacun des champs pr\u00e9vus \u00e0 cet effet du Formulaire d&#8217;Envoi de newsletters. L&#8217;Utilisateur a la possibilit\u00e9, \u00e0 tout moment, de refuser l&rsquo;envoi de newsletters par le lien correspondant dans la newsletter ou par l&rsquo;envoi d&rsquo;un message. L&#8217;adresse de courrier \u00e9lectronique sera alors effac\u00e9e de la liste de distribution de Groupe SOS Transition \u00c9cologique et Territoires.<\/li>\n<li>Les nom, pr\u00e9nom et adresse de courrier \u00e9lectronique en vue d&#8217;entrer en contact avec un interlocuteur de Groupe SOS Transition \u00c9cologique et Territoires. La d\u00e9claration de Consentement passe par la transmission volontaire de ces informations de l&#8217;Utilisateur dans chacun des champs pr\u00e9vus \u00e0 cet effet du Formulaire de Contact.<\/li>\n<li>Toute autre information constituant des Donn\u00e9es Personnelles au sens de la R\u00e9glementation Applicable renseign\u00e9e volontairement dans la partie &laquo; Laissez votre message &raquo; du Formulaire de Contact , le formulaire candidature spontan\u00e9e et par tout autre moyen appropri\u00e9.<\/li>\n<li>Les donn\u00e9es de navigation telles que d\u00e9taill\u00e9es \u00e0 l&#8217;Article 9 ci-dessous<\/li>\n<\/ul>\n<p><strong>4.2 Concernant les  <\/strong><\/p>\n<ul>\n<li>Les donn\u00e9es d&#8217;identification recueillies lors de la cr\u00e9ation d&#8217;un Compte Membre et notamment, noms, pr\u00e9noms, adresses de courrier \u00e9lectroniques et mot de passe encrypt\u00e9.<\/li>\n<li>Les informations constituant des Donn\u00e9es Personnelles au sens de la R\u00e9glementation Applicable volontairement renseign\u00e9es par le Membre dans le Formulaire de Gestion du Compte, et notamment le num\u00e9ro de t\u00e9l\u00e9phone, l&#8217;URL Facebook, Twitter ou LinkedIn, la fonction, et les centres d&#8217;int\u00e9r\u00eats, permettant de mieux conna\u00eetre le Membre.<\/li>\n<li>Les nom, pr\u00e9nom et adresse de courrier \u00e9lectronique du Membre en vue de recevoir la newsletter de Groupe SOS Transition \u00c9cologique et Territoires. La d\u00e9claration de Consentement passe par la transmission volontaire de ces informations du Membre dans chacun des champs pr\u00e9vus \u00e0 cet effet du Formulaire d&#8217;Envoi de newsletters. Le Membre a la possibilit\u00e9, \u00e0 tout moment, de refuser l&rsquo;envoi de newsletters par le lien correspondant dans la newsletter ou par l&rsquo;envoi d&rsquo;un message. L&#8217;adresse de courrier \u00e9lectronique sera alors effac\u00e9e de la liste de distribution de Groupe SOS Transition \u00c9cologique et Territoires.<\/li>\n<li>Les nom, pr\u00e9nom et adresse de courrier \u00e9lectronique en vue d&#8217;entrer en contact avec un interlocuteur de Groupe SOS Transition \u00c9cologique et Territoires. La d\u00e9claration de Consentement passe par la transmission volontaire de ces informations du Membre dans chacun des champs pr\u00e9vus \u00e0 cet effet du Formulaire de Contact.<\/li>\n<li>Toute autre information constituant des Donn\u00e9es Personnelles au sens de la R\u00e9glementation Applicable renseign\u00e9e volontairement dans la partie &laquo; Laissez votre message &raquo; du Formulaire de Contact ou le formulaire de candidature spontan\u00e9e et par tout autre moyen appropri\u00e9.<\/li>\n<li>Les donn\u00e9es de navigation telles que d\u00e9taill\u00e9es \u00e0 l&#8217;Article 9 ci-dessous.<\/li>\n<\/ul>\n<h2>5. Les destinataires des donn\u00e9es personnelles<\/h2>\n<p>La base de Donn\u00e9es Personnelles constitu\u00e9e \u00e0 l&#8217;occasion de votre utilisation des Services est strictement confidentielle. Le Groupe SOS Transition \u00c9cologique et Territoires s&#8217;engage \u00e0 prendre toutes les pr\u00e9cautions utiles, mesures organisationnelles et techniques appropri\u00e9es pour pr\u00e9server la s\u00e9curit\u00e9, l&#8217;int\u00e9grit\u00e9 et la confidentialit\u00e9 des Donn\u00e9es Personnelles, et notamment emp\u00eacher qu&#8217;elles soient d\u00e9form\u00e9es, endommag\u00e9es ou que des Tiers non autoris\u00e9s y aient acc\u00e8s.<\/p>\n<p><\/p>\n<p><strong>5.1 Donn\u00e9es transf\u00e9r\u00e9es aux autorit\u00e9s et\/ou organismes publics<\/strong><\/p>\n<p>Conform\u00e9ment \u00e0 la R\u00e9glementation Applicable, les Donn\u00e9es Personnelles peuvent \u00eatre transmises aux autorit\u00e9s comp\u00e9tentes sur requ\u00eate et notamment aux organismes publics, exclusivement pour r\u00e9pondre aux obligations l\u00e9gales, les auxiliaires de justice, les officiers minist\u00e9riels et les organismes charg\u00e9s d&#8217;effectuer le recouvrement de cr\u00e9ances.<\/p>\n<p><strong>5.2 Donn\u00e9es accessibles \u00e0 des Tiers<\/strong><\/p>\n<p>Les Donn\u00e9es Personnelles pourront \u00eatre utilis\u00e9es par le Groupe SOS Transition \u00c9cologique et Territoires, ses Sous-Traitants, les co-Responsables du Traitement ses affili\u00e9s et\/ou, le cas \u00e9ch\u00e9ant, par ses partenaires, pour les finalit\u00e9s d\u00e9crites \u00e0 l&#8217;Article 3 ci-dessus.<\/p>\n<p><\/p>\n<ul>\n<li>Le personnel habilit\u00e9 de Groupe SOS Transition \u00c9cologique et Territoires de par leurs fonctions, les services charg\u00e9s du contr\u00f4le (commissaire aux comptes notamment) et les sous-traitants de Groupe SOS Transition \u00c9cologique et Territoires auront acc\u00e8s aux Donn\u00e9es Personnelles collect\u00e9es dans le cadre de l&#8217;utilisation des Services ;<\/li>\n<li>Les partenaires de Groupe SOS Transition \u00c9cologique et Territoires qui l&#8217;assistent dans la fourniture des Services ; \u00b7 R\u00e9seaux sociaux : si l&rsquo;Utilisateur poss\u00e8de un compte sur des sites des r\u00e9seaux sociaux et qu&rsquo;il acc\u00e8de aux Services, ceux-ci peuvent inclure des plugiciels (plugins) tels que des boutons &laquo; J&#8217;aime &raquo; ou des boutons de partage ou de redirection, permettant de publier des contenus des Services sur les r\u00e9seaux sociaux. Le cas \u00e9ch\u00e9ant, les r\u00e9seaux sociaux concern\u00e9s peuvent recevoir des informations relatives \u00e0 l&#8217;utilisation des Services par l&#8217;Utilisateur.<\/li>\n<\/ul>\n<p><strong>5.3 Transferts hors de l&#8217;Union Europ\u00e9enne<\/strong><\/p>\n<p>Les Donn\u00e9es Personnelles de l&#8217;Utilisateur peut \u00eatre Trait\u00e9es en dehors de l&#8217;Union Europ\u00e9enne, y compris via un acc\u00e8s \u00e0 distance. Le Groupe SOS Transition \u00c9cologique et Territoires s&#8217;engage \u00e0 ne r\u00e9aliser aucun transfert des Donn\u00e9es Personnelles hors de l&#8217;Union Europ\u00e9enne sans mettre en \u0153uvre les garanties appropri\u00e9es conform\u00e9ment \u00e0 la R\u00e9glementation Applicable.<\/p>\n<h2>6. Les droits de l&#8217;utilisateur et du membre<\/h2>\n<p>Sous r\u00e9serve d&#8217;une demande expresse et de justifier de leur identit\u00e9 aupr\u00e8s Groupe SOS Transition \u00c9cologique et Territoires, l&#8217;Utilisateur dispose d&#8217;un droit d&#8217;acc\u00e8s, de rectification et d&rsquo;opposition sur leurs Donn\u00e9es Personnelles, ainsi qu&#8217;un droit \u00e0 l&#8217;effacement, dans les conditions de la R\u00e9glementation Applicable, en s&#8217;adressant \u00e0 Groupe SOS Transition \u00c9cologique et Territoires \u00e0 l&#8217;adresse postale ou \u00e9lectronique mentionn\u00e9es \u00e0 l&#8217;Article 10 ci-dessous.<\/p>\n<p>En cas d&#8217;exercice du droit d&#8217;opposition, Le Groupe SOS Transition \u00c9cologique et Territoires cessera le Traitement des Donn\u00e9es Personnelles, sauf en cas de motif(s) l\u00e9gitime(s) et imp\u00e9rieux pour le Traitement, ou pour assurer la constatation, l&#8217;exercice ou la d\u00e9fense de ses droits en justice, conform\u00e9ment \u00e0 la R\u00e9glementation Applicable. Le cas \u00e9ch\u00e9ant, Le Groupe SOS Transition \u00c9cologique et Territoires informera l&#8217;Utilisateur des motifs pour lesquels les droits qu&#8217;il exerce ne sauraient \u00eatre satisfaits en tout ou partie.<\/p>\n<p>Sous r\u00e9serve d&#8217;une demande expresse et de justifier de leur identit\u00e9 aupr\u00e8s de Groupe SOS Transition \u00c9cologique et Territoires, l&#8217;Utilisateur dispose \u00e9galement du droit de r\u00e9cup\u00e9rer leurs Donn\u00e9es Personnelles dans un format structur\u00e9, couramment utilis\u00e9 et lisible par machine, afin de les transmettre \u00e0 un autre Responsable du Traitement.<\/p>\n<p>L&#8217;Utilisateur a la facult\u00e9 de fournir \u00e0 Groupe SOS Transition \u00c9cologique et Territoires des directives relatives au sort de leurs Donn\u00e9es Personnelles apr\u00e8s leur d\u00e9c\u00e8s.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, le Groupe SOS Transition \u00c9cologique et Territoires informera l&#8217;Utilisateur des motifs pour lesquels les droits qu&#8217;il exerce ne sauraient \u00eatre satisfaits en tout ou en partie.<\/p>\n<h2>7. La dur\u00e9e de conservation des donn\u00e9es personnelles<\/h2>\n<p>Les Donn\u00e9es Personnelles des Utilisateurs et des   ne sont pas conserv\u00e9es au-del\u00e0 de la dur\u00e9e strictement n\u00e9cessaire aux finalit\u00e9s poursuivies telles qu&rsquo;\u00e9nonc\u00e9es \u00e0 l&#8217;Article 3 ci-dessus, conform\u00e9ment \u00e0 la R\u00e9glementation Applicable. Notamment :<\/p>\n<p><\/p>\n<ul>\n<li>Les Donn\u00e9es Personnelles recueillies pour g\u00e9rer les demandes d&#8217;opposition au Traitement sont stock\u00e9es dans un d\u00e9lai de 5 (cinq) ans maximum \u00e0 compter de la cl\u00f4ture de la demande d&#8217;opposition ;<\/li>\n<li>Les Donn\u00e9es Personnelles Trait\u00e9es pour g\u00e9rer les demandes d&#8217;acc\u00e8s et de rectification des Donn\u00e9es Personnelles sont stock\u00e9es dans un d\u00e9lai maximum de 5 (cinq) ans maximum \u00e0 compter de la cl\u00f4ture des demandes ;<\/li>\n<li>Les Donn\u00e9es Personnelles r\u00e9colt\u00e9es \u00e0 des fins d&#8217;envoi d&#8217;informations ou d&#8217;offres (notamment par l&#8217;envoi de newsletters) sont stock\u00e9es dans un d\u00e9lai maximum de 3 (trois) ans apr\u00e8s le dernier contact entre Groupe SOS Transition \u00c9cologique et Territoires et l&#8217;Utilisateur ;<\/li>\n<li>Les Donn\u00e9es Personnelles relatives \u00e0 la gestion des interactions avec des interlocuteurs de Groupe SOS Transition \u00c9cologique et Territoires (notamment par la rubrique &laquo; Contact &raquo;) sont conserv\u00e9es dans un d\u00e9lai maximum de 3 (trois) ans \u00e0 compter de la derni\u00e8re interaction initi\u00e9e par l&#8217;Utilisateur.<\/li>\n<\/ul>\n<p>Les Donn\u00e9es Personnelles pourront \u00eatre archiv\u00e9es au-del\u00e0 des d\u00e9lais d\u00e9crits ci-dessus dans la mesure o\u00f9 ils sont n\u00e9cessaires pour les besoins de la recherche, la constatation, et de la poursuite des infractions p\u00e9nales dans le seul but de permettre, en tant que de besoin, la mise \u00e0 disposition de ces Donn\u00e9es Personnelles \u00e0 l&#8217;autorit\u00e9 judiciaire, ou encore pour d&#8217;autres obligations de conservation, notamment \u00e0 des fins comptables ou fiscales. L&rsquo;archivage implique que ces Donn\u00e9es Personnelles feront l&#8217;objet de restrictions d&#8217;acc\u00e8s et seront conserv\u00e9es sur un support autonome et s\u00e9curis\u00e9.<\/p>\n<h2>8. S\u00e9curit\u00e9<\/h2>\n<p>Conform\u00e9ment \u00e0 la R\u00e9glementation Applicable, Groupe SOS Transition \u00c9cologique et Territoires Traite les Donn\u00e9es Personnelles en toute s\u00e9curit\u00e9 et confidentialit\u00e9.<\/p>\n<p>En particulier, Groupe SOS Transition \u00c9cologique et Territoires met en \u0153uvre toutes les mesures techniques et organisationnelles n\u00e9cessaires pour garantir la s\u00e9curit\u00e9 et la confidentialit\u00e9 des Donn\u00e9es Personnelles collect\u00e9es et Trait\u00e9es, et notamment emp\u00eacher qu&rsquo;elles soient d\u00e9form\u00e9es, endommag\u00e9es ou communiqu\u00e9es \u00e0 des Tiers non autoris\u00e9s, en assurant un niveau de s\u00e9curit\u00e9 adapt\u00e9 aux risques li\u00e9s au Traitement et \u00e0 la nature des Donn\u00e9es Personnelles \u00e0 prot\u00e9ger, eu \u00e9gard au niveau technologique et au co\u00fbt de mise en \u0153uvre.<\/p>\n<p>Groupe SOS Transition \u00c9cologique et Territoires ne peut toutefois garantir la confidentialit\u00e9 des Donn\u00e9es Personnelles rendues publiques par l&#8217;Utilisateur dans les parties publiques du Site et des Services.<\/p>\n<p>Le Site est susceptible d&#8217;inclure des liens vers des sites Internet ou des sources externes. L&#8217;Utilisateur reconna\u00eet que la Charte ne s&#8217;applique que pour les Services et l&#8217;utilisation des Sites, et ne couvre en aucun cas les informations collect\u00e9es et\/ou Trait\u00e9es sur les sites ou sources externes, dont le lien figure sur le Site. En cons\u00e9quence, Groupe SOS Transition \u00c9cologique et Territoires ne saurait \u00eatre Responsable des pratiques de ces sites ou sources externes en mati\u00e8re de collecte et de Traitement de Donn\u00e9es Personnelles, qui sont r\u00e9gies, le cas \u00e9ch\u00e9ant, par les chartes de donn\u00e9es personnelles propre \u00e0 chacun de ces sites ou sources externes.<\/p>\n<h2>9. Politique de cookies<\/h2>\n<p>Notre site web, apiaforautism.org utilise des cookies et d\u2019autres technologies connexes (par commodit\u00e9, toutes les technologies sont d\u00e9sign\u00e9es par le terme \u00ab cookies \u00bb). Des cookies sont \u00e9galement plac\u00e9s par des tiers que nous avons engag\u00e9s. Dans le document ci-dessous, nous vous informons de l\u2019utilisation des cookies sur notre site web.<\/p>\n<p><strong>9.1 Qu&#8217;est-ce qu&#8217;un cookie ?<\/strong><\/p>\n<p>Parmi les Donn\u00e9es Personnelles, Groupe SOS Transition \u00c9cologique et Territoires est amen\u00e9e \u00e0 collecter des donn\u00e9es r\u00e9sultant du d\u00e9p\u00f4t de cookies.<\/p>\n<p>Un cookie est un petit fichier texte, image ou logiciel, qui est plac\u00e9 et stock\u00e9 sur l&#8217;ordinateur ou le smartphone de l&#8217;Utilisateur, ainsi que sur tout appareil leur permettant de naviguer sur Internet (&laquo; Terminal &raquo;).<\/p>\n<p>Tr\u00e8s utiles, les cookies permettent \u00e0 un site Internet de reconnaitre l&#8217;Utilisateur de signaler leur passage sur telle ou telle page et de leur apporter ainsi un service additionnel : l&#8217;am\u00e9lioration de leur confort de navigation, la s\u00e9curisation de leur connexion ou l&#8217;adaptation du contenu d&#8217;une page \u00e0 leurs centres d&#8217;int\u00e9r\u00eat.<\/p>\n<p>Les informations enregistr\u00e9es par les cookies, pendant une dur\u00e9e de validit\u00e9 limit\u00e9e, portent notamment sur les pages visit\u00e9es, les publicit\u00e9s sur lesquelles l&#8217;Utilisateur a cliqu\u00e9, le type de navigateur qu&#8217;ils utilisent, leur adresse IP, les informations qu&#8217;ils ont saisies sur les Services (afin d\u2018\u00e9viter de les saisir \u00e0 nouveau).<\/p>\n<p>Les cookies ne sont pas des dossiers actifs, et ne peuvent donc pas h\u00e9berger de virus. Pour en savoir plus, vous pouvez vous rendre sur <a href=\"http:\/\/www.allaboutcookies.org\/\" target=\"_blank\" rel=\"noopener\">www.allaboutcookies.org<\/a>.\n<\/p>\n<p><strong>9.2 &#8211; Qu\u2019est-ce qu\u2019un script ? <\/strong><\/p>\n<p>Un script est un morceau de code de programme qui est utilis\u00e9 pour faire fonctionner notre site web correctement et de mani\u00e8re interactive. Ce code est ex\u00e9cut\u00e9 sur notre serveur ou sur votre appareil.<\/p>\n<p><strong>9.3 &#8211; Qu\u2019est-ce qu\u2019une balise web ? <\/strong><\/p>\n<p>Une balise web (ou pixel tag) est un petit \u00e9l\u00e9ment invisible de texte ou d\u2019image sur un site web qui est utilis\u00e9 pour surveiller le trafic sur un site web. Pour ce faire, diverses donn\u00e9es vous concernant sont stock\u00e9es \u00e0 l\u2019aide de balises web.<\/p>\n<p><\/p>\n<p><strong>9.4 A quoi servent les cookies \u00e9mis sur les Sites ?<\/strong><\/p>\n<p>Seul l&#8217;\u00e9metteur d&#8217;un cookie est susceptible de lire ou de modifier des informations qui y sont contenues.<\/p>\n<p>Les cookies sont utilis\u00e9s aux fins d\u00e9crites ci-dessous, sous r\u00e9serve de vos choix que vous pouvez exprimer et modifier \u00e0 tout moment via les param\u00e8tres du logiciel de navigation utilis\u00e9 lors de votre navigation sur les Sites (ci-apr\u00e8s les &laquo; Cookies &raquo;).<\/p>\n<p><\/p>\n<p><strong>9.4.1 Les Cookies de navigation<\/strong><\/p>\n<p>Les Cookies de navigation permettent d&#8217;am\u00e9liorer les performances de Groupe SOS Transition \u00c9cologique et Territoires afin de fournir une meilleure utilisation des Sites. Ces Cookies ne requi\u00e8rent pas l&#8217;information de l&#8217;Utilisateur, ni leur accord pr\u00e9alable pour \u00eatre d\u00e9pos\u00e9s sur le Terminal.<\/p>\n<p>Les Cookies de navigation permettent :<\/p>\n<p>\u00b7 d&#8217;adapter la pr\u00e9sentation des Sites aux pr\u00e9f\u00e9rences d&#8217;affichage du Terminal (par exemple, langue utilis\u00e9e, r\u00e9solution d&#8217;affichage, syst\u00e8me d&#8217;exploitation utilis\u00e9, etc.) lors des visites de Utilisateurs, sur les Sites, selon les mat\u00e9riels et les logiciels de visualisation ou de lecture que le Terminal comporte ;<\/p>\n<p>\u00b7 de m\u00e9moriser les pr\u00e9f\u00e9rences d&#8217;utilisation, les param\u00e8tres d&#8217;affichage et lecteurs que les Utilisateur utilise afin de faciliter leur navigation lors de leur prochaine visite sur les Sites. Ils permettent notamment l&#8217;acc\u00e8s \u00e0 un espace r\u00e9serv\u00e9 soumis \u00e0 un identifiant ou un mot de passe ;<\/p>\n<p>\u00b7 de m\u00e9moriser les informations saisies sur certains formulaires pr\u00e9sents sur le Site afin d&#8217;\u00e9viter de les renseigner de nouveau lors de leur prochaine visite.<\/p>\n<p><strong>9.4.2 Les Cookies statistiques<\/strong><\/p>\n<p>Afin d&#8217;adapter les Sites aux besoins de l&#8217;Utilisateur, Groupe SOS Transition \u00c9cologique et Territoires mesure le nombre de visites, le nombre de pages consult\u00e9es ainsi que de l&#8217;activit\u00e9 de l&#8217;Utilisateur sur les Sites et leur fr\u00e9quence de retour. Ces Cookies permettent d&#8217;\u00e9tablir des statistiques d&#8217;analyse de la fr\u00e9quentation \u00e0 partir desquels les contenus des Sites sont am\u00e9lior\u00e9s en fonction du succ\u00e8s rencontr\u00e9 par telle ou telle page aupr\u00e8s des Utilisateurs ou des  .<\/p>\n<p>Les r\u00e9sultats de ces analyses sont Trait\u00e9es de mani\u00e8re anonyme et \u00e0 des fins exclusivement statistiques.<\/p>\n<p>\n  <table style=\"width: 100%;height: 232px\">\n<tbody>\n<tr style=\"height: 48px\">\n<td style=\"height: 48px\">\u00c9metteur du Cookie<\/td>\n<td style=\"height: 48px\">Nom du Cookie<\/td>\n<td style=\"height: 48px\">Finalit\u00e9 du Cookie<\/td>\n<td style=\"height: 48px\">Opt-out (renvoi vers les proc\u00e9dures d&#8217;opt-out le cas \u00e9ch\u00e9ant)<\/td>\n<td style=\"height: 48px\">Dur\u00e9e de vie du Cookie<\/td>\n<\/tr>\n<tr style=\"height: 56px\">\n<td style=\"height: 56px\"><\/td>\n<td style=\"height: 56px\">MATOMO_SESSID<\/td>\n<td style=\"height: 56px\">Il est important de noter qu&#8217;il ne contient aucune donn\u00e9e permettant d&#8217;identifier les visiteurs et est consid\u00e9r\u00e9 comme un cookie \u00ab Essentiel \u00bb<\/td>\n<td style=\"height: 56px\"><\/td>\n<td style=\"height: 56px\">14 jours<\/td>\n<\/tr>\n<tr style=\"height: 56px\">\n<td style=\"height: 56px\"><\/td>\n<td style=\"height: 56px\">_pk_id<\/td>\n<td style=\"height: 56px\">\u00a0Ce cookie est utilis\u00e9 pour stocker quelques d\u00e9tails sur l&#8217;utilisateur tels que l&#8217;identifiant unique du visiteur<\/td>\n<td style=\"height: 56px\"><\/td>\n<td style=\"height: 56px\">13 mois<\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"height: 24px\"><\/td>\n<td style=\"height: 24px\">_pk_ses<\/td>\n<td style=\"height: 24px\">Ce cookie est de courte dur\u00e9e, il est utilis\u00e9 pour stocker temporairement les donn\u00e9es de la visite<\/td>\n<td style=\"height: 24px\"><\/td>\n<td style=\"height: 24px\">30 minutes<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/p>\n<p>&nbsp;<\/p>\n<p><strong>9.4.3  Les cookies techniques ou fonctionnels <\/strong><\/p>\n<p>Certains cookies permettent de garantir le bon fonctionnement de certaines parties du site web et de conserver vos pr\u00e9f\u00e9rences d\u2019utilisateur. En pla\u00e7ant des cookies fonctionnels, nous facilitons votre visite sur notre site web. Ainsi, vous ne devez pas saisir plusieurs fois les m\u00eames informations lorsque vous visitez notre site web et, par exemple, les articles restent dans votre panier d\u2019achat jusqu\u2019\u00e0 ce que vous ayez pay\u00e9. Nous pouvons placer ces cookies sans votre consentement.<\/p>\n<p><strong>9.4.4 Cookies de marketing\/suivi <\/strong><\/p>\n<p>Les cookies de marketing\/suivi sont des cookies ou toute autre forme de stockage local, utilis\u00e9s pour cr\u00e9er des profils d\u2019utilisateurs afin d\u2019afficher de la publicit\u00e9 ou de suivre l\u2019utilisateur sur ce site web ou sur plusieurs sites web \u00e0 des fins de marketing similaires.\n<\/p>\n<p><strong>9.5 Dur\u00e9e de validit\u00e9 des Cookies<\/strong><\/p>\n<p>Les Cookies \u00e9mis sur les Sites sont des Cookies de session (dont la dur\u00e9e est limit\u00e9e au temps d&#8217;une connexion aux Sites) et des Cookies persistants (dont la dur\u00e9e, toutefois limit\u00e9e, est sup\u00e9rieure \u00e0 la dur\u00e9e d&#8217;une connexion).<\/p>\n<p>Les Cookies de session ne sont actifs que le temps de la visite et sont supprim\u00e9s lorsque l&#8217;Utilisateur ferme son navigateur. Les Cookies persistants restent enregistr\u00e9s sur le disque dur du Terminal de l&#8217;Utilisateur une fois son navigateur ferm\u00e9.<\/p>\n<p>Conform\u00e9ment \u00e0 la R\u00e9glementation Applicable et aux recommandations de la Commission Nationale Informatique et Libert\u00e9s (&laquo; CNIL &raquo;), les Cookies sont conserv\u00e9s pour une dur\u00e9e maximale de 13 (treize) mois apr\u00e8s leur premier d\u00e9p\u00f4t. A l&#8217;expiration de ce d\u00e9lai, le Consentement de l&#8217;Utilisateur devra \u00eatre recueilli de nouveau pour la collecte des Cookies soumis au Consentement.<\/p>\n<p><strong>9.6 Cookies utilis\u00e9s<\/strong><\/p>\n<p><p><strong>9.8 Cookies utilis\u00e9s<\/strong><\/p><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Functional, Funcional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WordPress para desarrollo de sitios web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\" aria-label=\"M\u00e1s informaci\u00f3n acerca del servicio WordPress en la base de datos de cookies\">Leer m\u00e1s acerca de WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_preferences_user_\/\">WP_PREFERENCES_USER_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Read if cookies can be placed<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Store logged in users<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar detalles del navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_lang\/\">wp_lang<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">sesi\u00f3n<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Guardar configuraciones de lenguaje<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WPML para gesti\u00f3n local. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wpml\/\" aria-label=\"M\u00e1s informaci\u00f3n acerca del servicio WPML en la base de datos de cookies\">Leer m\u00e1s acerca de WPML<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wpml\/wp-wpml_current_language\/\">wp-wpml_current_language<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 day<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Store language settings<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Wordfence<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wordfence\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordfence<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordfence\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordfence\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Wordfence para seguridad del sitio web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordfence\/\" aria-label=\"M\u00e1s informaci\u00f3n acerca del servicio Wordfence en la base de datos de cookies\">Leer m\u00e1s acerca de Wordfence<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.wordfence.com\/privacy-policy\/\">pol\u00edtica de privacidad de Wordfence<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordfence\/wfwaf-authcookie\/\">wfwaf-authcookie*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 day<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Read to determine if the user is logged in<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varios<\/h3>\n\t\t<p>Prop\u00f3sito pendiente de investigaci\u00f3n<\/p>\n\t\t<label for=\"cmplz_service_varios\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varios<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varios\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varios\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>El intercambio de datos est\u00e1 pendiente de investigaci\u00f3n<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">mtnc_upsell_shown<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">mtnc_upsell_shown_timestamp<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_34393536-3439-5434-a232-626235363365<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">loglevel<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_wp_first_time<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_3<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><\/p>\n<p><strong>9.7 Vos choix concernant les Cookies<\/strong><\/p>\n<p>L&#8217;ensemble des droits reconnus \u00e0 l&#8217;Article 6 ci-dessus sont \u00e9galement applicables \u00e0 l&#8217;Utilisateur.<\/p>\n<p>Plusieurs possibilit\u00e9s leurs sont offertes pour g\u00e9rer les Cookies. L&#8217;Utilisateur comprend que les Cookies am\u00e9liorent le confort de navigation sur les Sites et sont indispensables pour acc\u00e9der \u00e0 certains espaces s\u00e9curis\u00e9s. Tout param\u00e9trage que l&#8217;Utilisateur peut entreprendre sera susceptible de modifier sa navigation sur les Sites et ses conditions d&#8217;acc\u00e8s \u00e0 certains services n\u00e9cessitant l&#8217;utilisation de Cookies. Groupe SOS Transition \u00c9cologique et Territoires ne saurait \u00eatre tenue pour responsable des cons\u00e9quences d&#8217;un fonctionnement moins efficace des Sites d\u00fb \u00e0 l&#8217;impossibilit\u00e9 d&#8217;installer ou de lire des Cookies n\u00e9cessaires \u00e0 leur bon fonctionnement, d\u00e8s lors que l&#8217;Utilisateur les a rejet\u00e9s ou supprim\u00e9s.<\/p>\n<p>Les Utilisateurs et les   peuvent configurer leur logiciel de navigation de mani\u00e8re \u00e0 ce que les Cookies soient enregistr\u00e9s dans leur Terminal ou, au contraire, rejet\u00e9s, soit syst\u00e9matiquement, soit selon leur \u00e9metteur. Les Utilisateurs et les   peuvent \u00e9galement configurer leur logiciel de navigation de mani\u00e8re \u00e0 ce que l&#8217;acceptation ou le refus des Cookies leur soit propos\u00e9s ponctuellement, avant qu&#8217;un Cookie soit susceptible d&#8217;\u00eatre enregistr\u00e9 sur leur Terminal.<\/p>\n<p>Le menu d&rsquo;aide ou la rubrique d\u00e9di\u00e9e de votre navigateur vous permettra de savoir de quelle mani\u00e8re exprimer ou modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de Cookies :<\/p>\n<p>\u00b7 Pour Internet Explorer\u2122 :<\/p>\n<p><\/p>\n<p><a href=\"http:\/\/windows.microsoft.com\/fr-FR\/windows-vista\/Block-or-allow-cookies\" target=\"_blank\" rel=\"noopener\">http:\/\/windows.microsoft.com\/fr-FR\/windows-vista\/Block-or-allow-cookies<\/a><\/p>\n<p><\/p>\n<p>\u00b7 Pour Safari\u2122 :<\/p>\n<p><a href=\"https:\/\/support.apple.com\/fr-fr\/guide\/safari\/sfri11471\/mac\" target=\"_blank\" rel=\"noopener\">https:\/\/support.apple.com\/fr-fr\/guide\/safari\/sfri11471\/mac<\/a><\/p>\n<p><\/p>\n<p>\u00b7 Pour Chrome\u2122 :<\/p>\n<p><a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=fr&amp;hlrm=en&amp;answer=95647\" target=\"_blank\" rel=\"noopener\">http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=fr&amp;hlrm=en&amp;answer=95647<\/a><\/p>\n<p>\u00b7 Pour Firefox\u2122 :<\/p>\n<p><a href=\"http:\/\/support.mozilla.org\/fr\/kb\/Activer%20et%20d%C3%A9sactiver%20les%20cookies\" target=\"_blank\" rel=\"noopener\">http:\/\/support.mozilla.org\/fr\/kb\/Activer%20et%20d%C3%A9sactiver%20les%20cookies<\/a><\/p>\n<p>\u00b7 Pour Opera\u2122 :<\/p>\n<p><a href=\"https:\/\/help.opera.com\/en\/latest\/web-preferences\/#cookies\" target=\"_blank\" rel=\"noopener\">https:\/\/help.opera.com\/en\/latest\/web-preferences\/#cookies<\/a><\/p>\n<p>\u00b7 Pour iOS :<\/p>\n<p><a href=\"https:\/\/support.apple.com\/fr-fr\/HT201265\" target=\"_blank\" rel=\"noopener\">https:\/\/support.apple.com\/fr-fr\/HT201265<\/a><\/p>\n<p><\/p>\n<p>\u00b7 Pour Android :<\/p>\n<p><a href=\"https:\/\/support.google.com\/accounts\/answer\/61416?co=GENIE.Platform%3DAndroid&amp;hl=fr\" target=\"_blank\" rel=\"noopener\">https:\/\/support.google.com\/accounts\/answer\/61416?co=GENIE.Platform%3DAndroid&amp;hl=fr<\/a><\/p>\n<p>\u00b7 Pour Blackberry :<\/p>\n<p><a href=\"https:\/\/global.blackberry.com\/fr\/legal\/cookies\" target=\"_blank\" rel=\"noopener\">https:\/\/global.blackberry.com\/fr\/legal\/cookies<\/a><\/p>\n<p>\u00b7 Pour Windows Phone :<\/p>\n<p><a href=\"https:\/\/support.microsoft.com\/fr-fr\/help\/17442\/windows-internet-explorer-delete-manage-cookies\" target=\"_blank\" rel=\"noopener\">https:\/\/support.microsoft.com\/fr-fr\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/a><\/p>\n<p>Pour une meilleure connaissance et ma\u00eetrise des Cookies de toute origine et pas seulement ceux de notre Site, l&#8217;Utilisateur et les   sont invit\u00e9s \u00e0 consulter le site Youronlinechoices, \u00e9dit\u00e9 par l&#8217;Interactive Advertising Bureau France (IAB) afin de connaitre les entreprises inscrites \u00e0 cette plate-forme et qui offrent la possibilit\u00e9 de refuser ou d&#8217;accepter les Cookies utilis\u00e9s par ces entreprises pour adapter les informations de navigation les publicit\u00e9s susceptibles d&#8217;\u00eatre affich\u00e9es sur le Terminal http:\/\/www.youronlinechoices.com\/be-fr\/controler-ses-cookies.<\/p>\n<p><strong>9.8 Consentement<\/strong><\/p>\n<p>Lorsque vous visitez notre site web pour la premi\u00e8re fois, nous affichons une fen\u00eatre contextuelle contenant des explications sur les cookies. D\u00e8s que vous cliquez sur  \u00bb Enregistrer les pr\u00e9f\u00e9rences \u00ab , vous consentez \u00e0 ce que nous utilisions les cat\u00e9gories de cookies et de plug-ins que vous avez s\u00e9lectionn\u00e9es dans la fen\u00eatre contextuelle, comme d\u00e9crit dans la pr\u00e9sente politique en mati\u00e8re de cookies. Vous pouvez d\u00e9sactiver l\u2019utilisation des cookies via votre navigateur, mais veuillez noter que notre site web pourrait ne plus fonctionner correctement. 7.1 <\/p>\n<p><strong>Gestion de vos param\u00e8tres de consentement<\/strong><\/p>\n<p><p><strong>Gestion de vos param\u00e8tres de consentement<\/strong><\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Has cargado la pol\u00edtica de cookies sin compatibilidad con JavaScript.&nbsp;En AMP, puedes utilizar el bot\u00f3n de gestionar el consentimiento en la parte inferior de la p\u00e1gina.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><\/p>\n<p>&nbsp;<\/p>\n<h2>10. CONTACT ET RECLAMATIONS<\/h2>\n<p>Pour toute demande ou en cas de diff\u00e9rend entre Groupe SOS Transition \u00c9cologique et Territoires et l&#8217;Utilisateur, concernant le Traitement de leurs Donn\u00e9es Personnelles, ces derniers peuvent adresser leur demande ou leur r\u00e9clamation \u00e0 Groupe SOS Transition \u00c9cologique et Territoires en la contactant \u00e0 l&#8217;adresse postale suivante : 102c rue Amelot 75011 Paris ou \u00e0 l&#8217;adresse de courrier \u00e9lectronique suivante <a href=\"mailto:contact-rgpd.transition-ecologique@groupe-sos.org\" rel=\"noopener\">contact-rgpd.transition-ecologique@groupe-sos.org<\/a><\/p>\n<p>Groupe SOS Transition \u00c9cologique et Territoires s&#8217;efforcera de trouver une solution satisfaisante pour assurer le respect de la R\u00e8glementation Applicable.<\/p>\n<p>En l&#8217;absence de r\u00e9ponse de Groupe SOS Transition \u00c9cologique et Territoires ou si le diff\u00e9rend persiste malgr\u00e9 la proposition du groupe l&#8217;Utilisateur a la possibilit\u00e9 d&#8217;introduire une r\u00e9clamation aupr\u00e8s de la CNIL ou de l&#8217;autorit\u00e9 de contr\u00f4le de l&#8217;\u00c9tat Membre de l&#8217;Union Europ\u00e9enne au sein duquel l&#8217;Utilisateur r\u00e9side habituellement et de mandater une association ou une organisation mentionn\u00e9e au IV de l&#8217;article 43 ter de la loi n\u00b078-17 du 6 janvier 1978 modifi\u00e9e.<\/p>\n   <\/div>\n  <\/div>\n\n <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3958","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de privacidad - Apia for autism<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad - Apia for autism\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Apia for autism\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T09:36:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/politique-de-confidentialite\\\/\",\"name\":\"Pol\u00edtica de privacidad - Apia for autism\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/#website\"},\"datePublished\":\"2024-10-04T12:37:46+00:00\",\"dateModified\":\"2024-10-30T09:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apiaforautism.org\\\/es\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/\",\"name\":\"Apia for autism\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/#organization\",\"name\":\"Apia for autism\",\"url\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apiaforautism.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-apia.png\",\"contentUrl\":\"https:\\\/\\\/apiaforautism.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-apia.png\",\"width\":218,\"height\":58,\"caption\":\"Apia for autism\"},\"image\":{\"@id\":\"https:\\\/\\\/apiaforautism.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - Apia for autism","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de privacidad - Apia for autism","og_url":"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/","og_site_name":"Apia for autism","article_modified_time":"2024-10-30T09:36:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/","url":"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/","name":"Pol\u00edtica de privacidad - Apia for autism","isPartOf":{"@id":"https:\/\/apiaforautism.org\/es\/#website"},"datePublished":"2024-10-04T12:37:46+00:00","dateModified":"2024-10-30T09:36:43+00:00","breadcrumb":{"@id":"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/apiaforautism.org\/es\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apiaforautism.org\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/apiaforautism.org\/es\/#website","url":"https:\/\/apiaforautism.org\/es\/","name":"Apia for autism","description":"","publisher":{"@id":"https:\/\/apiaforautism.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apiaforautism.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/apiaforautism.org\/es\/#organization","name":"Apia for autism","url":"https:\/\/apiaforautism.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/apiaforautism.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/apiaforautism.org\/wp-content\/uploads\/2024\/10\/logo-apia.png","contentUrl":"https:\/\/apiaforautism.org\/wp-content\/uploads\/2024\/10\/logo-apia.png","width":218,"height":58,"caption":"Apia for autism"},"image":{"@id":"https:\/\/apiaforautism.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/apiaforautism.org\/es\/wp-json\/wp\/v2\/pages\/3958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apiaforautism.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apiaforautism.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apiaforautism.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apiaforautism.org\/es\/wp-json\/wp\/v2\/comments?post=3958"}],"version-history":[{"count":1,"href":"https:\/\/apiaforautism.org\/es\/wp-json\/wp\/v2\/pages\/3958\/revisions"}],"predecessor-version":[{"id":3961,"href":"https:\/\/apiaforautism.org\/es\/wp-json\/wp\/v2\/pages\/3958\/revisions\/3961"}],"wp:attachment":[{"href":"https:\/\/apiaforautism.org\/es\/wp-json\/wp\/v2\/media?parent=3958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}